{"id":86074,"date":"2026-07-10T08:01:42","date_gmt":"2026-07-10T06:01:42","guid":{"rendered":"https:\/\/kd-ueberdachung.de\/?post_type=job&#038;p=86074"},"modified":"2026-07-15T10:51:22","modified_gmt":"2026-07-15T08:51:22","slug":"aussendienstmitarbeiter-in-m-w-d-saar-mosel","status":"publish","type":"job","link":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/","title":{"rendered":"Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 Saar\/Mosel"},"content":{"rendered":"","protected":false},"featured_media":7908,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"job-standort":[259],"class_list":["post-86074","job","type-job","status-publish","has-post-thumbnail","hentry","job-standort-saar-mosel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 Saar\/Mosel - KD \u00dcberdachung GmbH<\/title>\n<meta name=\"description\" content=\"KD \u00dcberdachung Saar\/Mosel sucht einen Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 jetzt bewerben und regional durchstarten! Wir freuen uns auf dich!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 Saar\/Mosel\" \/>\n<meta property=\"og:description\" content=\"KD \u00dcberdachung Saar\/Mosel sucht einen Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 jetzt bewerben und regional durchstarten! Wir freuen uns auf dich!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/\" \/>\n<meta property=\"og:site_name\" content=\"KD \u00dcberdachung GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T08:51:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kd-ueberdachung.de\/wp-content\/uploads\/_media\/unternehmen\/standorte\/detail\/header-ruesselsheim.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/\",\"url\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/\",\"name\":\"Au\u00dfendienstmitarbeiter\\\/in (m\\\/w\\\/d) \u2013 Saar\\\/Mosel - KD \u00dcberdachung GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kd-ueberdachung.de\\\/wp-content\\\/uploads\\\/_media\\\/unternehmen\\\/standorte\\\/detail\\\/header-ruesselsheim.jpg\",\"datePublished\":\"2026-07-10T06:01:42+00:00\",\"dateModified\":\"2026-07-15T08:51:22+00:00\",\"description\":\"KD \u00dcberdachung Saar\\\/Mosel sucht einen Au\u00dfendienstmitarbeiter\\\/in (m\\\/w\\\/d) \u2013 jetzt bewerben und regional durchstarten! Wir freuen uns auf dich!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kd-ueberdachung.de\\\/wp-content\\\/uploads\\\/_media\\\/unternehmen\\\/standorte\\\/detail\\\/header-ruesselsheim.jpg\",\"contentUrl\":\"https:\\\/\\\/kd-ueberdachung.de\\\/wp-content\\\/uploads\\\/_media\\\/unternehmen\\\/standorte\\\/detail\\\/header-ruesselsheim.jpg\",\"width\":1920,\"height\":500,\"caption\":\"KD R\u00fcsselsheim\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Au\u00dfendienstmitarbeiter\\\/in (m\\\/w\\\/d) \u2013 Saar\\\/Mosel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/\",\"name\":\"KD \u00dcberdachung GmbH\",\"description\":\"Ein Dach f\u00fcr Ihr Zuhause \u2013 Wir fertigen \u00dcberdachungen, Beschattungen, Carports und Markisen\",\"publisher\":{\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/#organization\",\"name\":\"KD \u00dcberdachung GmbH\",\"url\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kd-ueberdachung.de\\\/en\\\/job\\\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/kd-ueberdachung.de\\\/wp-content\\\/uploads\\\/_media\\\/_allgemein\\\/logo-footer.png\",\"contentUrl\":\"https:\\\/\\\/kd-ueberdachung.de\\\/wp-content\\\/uploads\\\/_media\\\/_allgemein\\\/logo-footer.png\",\"width\":300,\"height\":220,\"caption\":\"KD \u00dcberdachung GmbH\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 Saar\/Mosel - KD \u00dcberdachung GmbH","description":"KD \u00dcberdachung Saar\/Mosel sucht einen Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 jetzt bewerben und regional durchstarten! Wir freuen uns auf dich!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/","og_locale":"en_US","og_type":"article","og_title":"Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 Saar\/Mosel","og_description":"KD \u00dcberdachung Saar\/Mosel sucht einen Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 jetzt bewerben und regional durchstarten! Wir freuen uns auf dich!","og_url":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/","og_site_name":"KD \u00dcberdachung GmbH","article_modified_time":"2026-07-15T08:51:22+00:00","og_image":[{"width":1920,"height":500,"url":"https:\/\/kd-ueberdachung.de\/wp-content\/uploads\/_media\/unternehmen\/standorte\/detail\/header-ruesselsheim.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/","url":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/","name":"Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 Saar\/Mosel - KD \u00dcberdachung GmbH","isPartOf":{"@id":"https:\/\/kd-ueberdachung.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/#primaryimage"},"image":{"@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/#primaryimage"},"thumbnailUrl":"https:\/\/kd-ueberdachung.de\/wp-content\/uploads\/_media\/unternehmen\/standorte\/detail\/header-ruesselsheim.jpg","datePublished":"2026-07-10T06:01:42+00:00","dateModified":"2026-07-15T08:51:22+00:00","description":"KD \u00dcberdachung Saar\/Mosel sucht einen Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 jetzt bewerben und regional durchstarten! Wir freuen uns auf dich!","breadcrumb":{"@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/#primaryimage","url":"https:\/\/kd-ueberdachung.de\/wp-content\/uploads\/_media\/unternehmen\/standorte\/detail\/header-ruesselsheim.jpg","contentUrl":"https:\/\/kd-ueberdachung.de\/wp-content\/uploads\/_media\/unternehmen\/standorte\/detail\/header-ruesselsheim.jpg","width":1920,"height":500,"caption":"KD R\u00fcsselsheim"},{"@type":"BreadcrumbList","@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kd-ueberdachung.de\/en\/"},{"@type":"ListItem","position":2,"name":"Au\u00dfendienstmitarbeiter\/in (m\/w\/d) \u2013 Saar\/Mosel"}]},{"@type":"WebSite","@id":"https:\/\/kd-ueberdachung.de\/en\/#website","url":"https:\/\/kd-ueberdachung.de\/en\/","name":"KD \u00dcberdachung GmbH","description":"Ein Dach f\u00fcr Ihr Zuhause \u2013 Wir fertigen \u00dcberdachungen, Beschattungen, Carports und Markisen","publisher":{"@id":"https:\/\/kd-ueberdachung.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kd-ueberdachung.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/kd-ueberdachung.de\/en\/#organization","name":"KD \u00dcberdachung GmbH","url":"https:\/\/kd-ueberdachung.de\/en\/","logo":{"@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/#local-main-organization-logo"},"image":{"@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kd-ueberdachung.de\/en\/job\/aussendienstmitarbeiter-in-m-w-d-saar-mosel\/#local-main-organization-logo","url":"https:\/\/kd-ueberdachung.de\/wp-content\/uploads\/_media\/_allgemein\/logo-footer.png","contentUrl":"https:\/\/kd-ueberdachung.de\/wp-content\/uploads\/_media\/_allgemein\/logo-footer.png","width":300,"height":220,"caption":"KD \u00dcberdachung GmbH"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/kd-ueberdachung.de\/en\/wp-json\/wp\/v2\/job\/86074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kd-ueberdachung.de\/en\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/kd-ueberdachung.de\/en\/wp-json\/wp\/v2\/types\/job"}],"version-history":[{"count":7,"href":"https:\/\/kd-ueberdachung.de\/en\/wp-json\/wp\/v2\/job\/86074\/revisions"}],"predecessor-version":[{"id":94312,"href":"https:\/\/kd-ueberdachung.de\/en\/wp-json\/wp\/v2\/job\/86074\/revisions\/94312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kd-ueberdachung.de\/en\/wp-json\/wp\/v2\/media\/7908"}],"wp:attachment":[{"href":"https:\/\/kd-ueberdachung.de\/en\/wp-json\/wp\/v2\/media?parent=86074"}],"wp:term":[{"taxonomy":"job-standort","embeddable":true,"href":"https:\/\/kd-ueberdachung.de\/en\/wp-json\/wp\/v2\/job-standort?post=86074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}